{"id":40376,"date":"2023-09-17T16:40:04","date_gmt":"2023-09-17T13:40:04","guid":{"rendered":"https:\/\/uomosul.edu.iq\/arts\/?page_id=40376"},"modified":"2025-05-26T09:17:22","modified_gmt":"2025-05-26T06:17:22","slug":"%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b9%d9%86-%d9%82%d8%b3%d9%85-%d8%a7%d9%84%d8%aa%d8%b1%d8%ac%d9%85%d8%a9","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/arts\/%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b9%d9%86-%d9%82%d8%b3%d9%85-%d8%a7%d9%84%d8%aa%d8%b1%d8%ac%d9%85%d8%a9\/","title":{"rendered":"\u0645\u0646\u0627\u0647\u062c \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5><span style=\"color: #ff0000\"><strong>\u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0645\u062a\u0648\u0641\u0631\u0629 \u0641\u064a \u0627\u0644\u0642\u0633\u0645:<\/strong><\/span><br \/>\n\u062a\u062a\u0648\u0641\u0631 \u0627\u0644\u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0635\u0628\u0627\u062d\u064a\u0629 \u0648\u0627\u0644\u0645\u0633\u0627\u0626\u064a\u0629 \u0641\u064a \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629 \u0648\u0628\u0648\u0627\u0642\u0639 414 \u0637\u0627\u0644\u0628\u0627 \u0644\u0644\u062f\u0631\u0627\u0633\u062a\u064a\u0646,<br \/>\n\u0643\u0645\u0627 \u062a\u062a\u0648\u0641\u0631 \u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627 \u0644\u0644\u0645\u0627\u062c\u0633\u062a\u064a\u0631 \u0648\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647 \u0648\u0628\u0648\u0627\u0642\u0639 26 \u0637\u0627\u0644\u0628\u0627 \u0644\u0644\u062f\u0631\u0627\u0633\u062a\u064a\u0646 \u0644\u0644\u0639\u0627\u0645 2022-2023.<\/h5>\n<h5><span style=\"color: #ff0000\"><strong>\u0627\u0644\u0645\u0646\u0647\u0627\u062c \u0627\u0644\u062f\u0631\u0627\u0633\u064a \u0641\u064a \u0627\u0644\u0642\u0633\u0645:\u0627\u0644\u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0623\u0648\u0644\u064a\u0629\u00a0<\/strong><\/span><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-37990 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-300x128.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-300x128.png\" alt=\"\" width=\"799\" height=\"341\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27799%27%20height%3D%27341%27%20viewBox%3D%270%200%20799%20341%27%3E%3Crect%20width%3D%27799%27%20height%3D%27341%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-200x85.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-300x128.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-400x170.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-600x255.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1-800x340.png 800w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra1.png 880w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-37991 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2-300x118.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2-300x118.png\" alt=\"\" width=\"775\" height=\"305\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27775%27%20height%3D%27305%27%20viewBox%3D%270%200%20775%20305%27%3E%3Crect%20width%3D%27775%27%20height%3D%27305%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2-200x79.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2-300x118.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2-400x157.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2-600x236.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra2.png 751w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 775px) 100vw, 775px\" \/><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-37992 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-300x98.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-300x98.png\" alt=\"\" width=\"774\" height=\"253\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27774%27%20height%3D%27253%27%20viewBox%3D%270%200%20774%20253%27%3E%3Crect%20width%3D%27774%27%20height%3D%27253%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-200x66.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-300x98.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-400x131.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-600x197.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3.png 762w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 774px) 100vw, 774px\" \/><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-37993 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2-300x103.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2-300x103.png\" alt=\"\" width=\"766\" height=\"263\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27766%27%20height%3D%27263%27%20viewBox%3D%270%200%20766%20263%27%3E%3Crect%20width%3D%27766%27%20height%3D%27263%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2-200x69.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2-300x103.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2-400x138.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2-600x207.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra3-2.png 763w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 766px) 100vw, 766px\" \/><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-37994 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-300x121.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-300x121.png\" alt=\"\" width=\"754\" height=\"304\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27754%27%20height%3D%27304%27%20viewBox%3D%270%200%20754%20304%27%3E%3Crect%20width%3D%27754%27%20height%3D%27304%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-200x81.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-300x121.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-400x161.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-600x242.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4.png 768w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 754px) 100vw, 754px\" \/><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-37995 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2-300x117.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2-300x117.png\" alt=\"\" width=\"741\" height=\"289\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27741%27%20height%3D%27289%27%20viewBox%3D%270%200%20741%20289%27%3E%3Crect%20width%3D%27741%27%20height%3D%27289%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2-200x78.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2-300x117.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2-400x156.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2-600x234.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/tra4-2.png 768w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 741px) 100vw, 741px\" \/><\/h5>\n<h5><span style=\"color: #ff0000\"><strong>\u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627:<\/strong><\/span><\/h5>\n<h5><img decoding=\"async\" class=\"lazyload wp-image-38000 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-232x300.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-232x300.png\" alt=\"\" width=\"814\" height=\"1053\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27814%27%20height%3D%271053%27%20viewBox%3D%270%200%20814%201053%27%3E%3Crect%20width%3D%27814%27%20height%3D%271053%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-200x259.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-232x300.png 232w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-400x518.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-600x776.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-768x994.png 768w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-791x1024.png 791w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-800x1035.png 800w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-1187x1536.png 1187w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-1200x1553.png 1200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2023\/06\/\u0645\u0639\u0644\u0648\u0645\u0627\u062a-\u0642\u0633\u0645-\u0627\u0644\u062a\u0631\u062c\u0645\u0629-1583x2048.png 1583w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 814px) 100vw, 814px\" \/><span style=\"color: #ff0000\">\u0645\u0646\u0627\u0647\u062c \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629 \u0644\u0644\u0639\u0627\u0645 \u0627\u0644\u062f\u0631\u0627\u0633\u064a(\u0627\u0644\u0623\u0648\u0644\u064a\u0629) 2024-2025\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/\u0648\u062d\u062f\u0627\u062a-\u062f\u0631\u0627\u0633\u064a\u0629-\u0639\u0644\u064a\u0627-2024-2025.pdf\" rel=\"attachment wp-att-48991\">\u00a0 <img decoding=\"async\" class=\"lazyload aligncenter  wp-image-48991\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-300x78.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-300x78.png\" alt=\"\" width=\"185\" height=\"48\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27185%27%20height%3D%2748%27%20viewBox%3D%270%200%20185%2048%27%3E%3Crect%20width%3D%27185%27%20height%3D%2748%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-200x52.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-300x78.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-400x104.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-600x155.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-768x199.png 768w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6.png 788w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/a><\/span><\/h5>\n<h5><span style=\"color: #ff0000\">\u0645\u0646\u0627\u0647\u062c \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629 \u0644\u0644\u0639\u0627\u0645 \u0627\u0644\u062f\u0631\u0627\u0633\u064a(\u0627\u0644\u0639\u0644\u064a\u0627) 2024-2025\u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/\u0648\u062d\u062f\u0627\u062a-\u0648\u0633\u0627\u0639\u0627\u062a-\u0639\u0644\u064a\u0627-2024-2025.pdf\" rel=\"attachment wp-att-48991\"><img decoding=\"async\" class=\"lazyload wp-image-48991 aligncenter\" src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-300x78.png\" data-orig-src=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-300x78.png\" alt=\"\" width=\"188\" height=\"49\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27188%27%20height%3D%2749%27%20viewBox%3D%270%200%20188%2049%27%3E%3Crect%20width%3D%27188%27%20height%3D%2749%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-200x52.png 200w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-300x78.png 300w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-400x104.png 400w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-600x155.png 600w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6-768x199.png 768w, https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/13-6.png 788w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 188px) 100vw, 188px\" \/><\/a> \u00a0 \u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/arts\/wp-content\/uploads\/sites\/17\/2025\/05\/\u0648\u062d\u062f\u0627\u062a-\u062f\u0631\u0627\u0633\u064a\u0629-\u0639\u0644\u064a\u0627-2024-2025.pdf\" rel=\"attachment wp-att-48991\">\u00a0<\/a><\/span><\/h5>\n<blockquote><p>&nbsp;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0645\u062a\u0648\u0641\u0631\u0629 \u0641\u064a \u0627\u0644\u0642\u0633\u0645: \u062a\u062a\u0648\u0641\u0631 \u0627\u0644\u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0635\u0628\u0627\u062d\u064a\u0629 \u0648\u0627\u0644\u0645\u0633\u0627\u0626\u064a\u0629 \u0641\u064a \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629 \u0648\u0628\u0648\u0627\u0642\u0639 414 \u0637\u0627\u0644\u0628\u0627 \u0644\u0644\u062f\u0631\u0627\u0633\u062a\u064a\u0646, \u0643\u0645\u0627 \u062a\u062a\u0648\u0641\u0631 \u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627 \u0644\u0644\u0645\u0627\u062c\u0633\u062a\u064a\u0631 \u0648\u0627\u0644\u062f\u0643\u062a\u0648\u0631\u0627\u0647 \u0648\u0628\u0648\u0627\u0642\u0639 26 \u0637\u0627\u0644\u0628\u0627 \u0644\u0644\u062f\u0631\u0627\u0633\u062a\u064a\u0646 \u0644\u0644\u0639\u0627\u0645 2022-2023. \u0627\u0644\u0645\u0646\u0647\u0627\u062c \u0627\u0644\u062f\u0631\u0627\u0633\u064a \u0641\u064a \u0627\u0644\u0642\u0633\u0645:\u0627\u0644\u062f\u0631\u0627\u0633\u0629 \u0627\u0644\u0623\u0648\u0644\u064a\u0629\u00a0 \u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0644\u064a\u0627: \u0645\u0646\u0627\u0647\u062c \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629 \u0644\u0644\u0639\u0627\u0645 \u0627\u0644\u062f\u0631\u0627\u0633\u064a(\u0627\u0644\u0623\u0648\u0644\u064a\u0629) 2024-2025\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u0645\u0646\u0627\u0647\u062c \u0642\u0633\u0645 \u0627\u0644\u062a\u0631\u062c\u0645\u0629 \u0644\u0644\u0639\u0627\u0645 \u0627\u0644\u062f\u0631\u0627\u0633\u064a(\u0627\u0644\u0639\u0644\u064a\u0627) 2024-2025\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 &nbsp;<\/p>\n","protected":false},"author":24,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-40376","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/pages\/40376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/comments?post=40376"}],"version-history":[{"count":6,"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/pages\/40376\/revisions"}],"predecessor-version":[{"id":48999,"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/pages\/40376\/revisions\/48999"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/arts\/wp-json\/wp\/v2\/media?parent=40376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}