{"id":40564,"date":"2024-12-14T19:27:23","date_gmt":"2024-12-14T19:27:23","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/?page_id=40564"},"modified":"2025-05-24T21:10:07","modified_gmt":"2025-05-24T21:10:07","slug":"department-of-environmental-health-academic-program","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-health-academic-program\/","title":{"rendered":"Department of Environmental Health \\Academic program description"},"content":{"rendered":"<p>Academic program description 2023-2024\u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/environmentalscience\/wp-content\/uploads\/sites\/14\/2024\/10\/%D9%88%D8%B5%D9%81-%D8%A7%D9%84%D8%A8%D8%B1%D9%86%D8%A7%D9%85%D8%AC-%D8%A7%D9%84%D8%A7%D9%83%D8%A7%D8%AF%D9%8A%D9%85%D9%8A.pdf\">Click here<\/a><\/p>\n<p>Academic program description 2024-2025\u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/environmentalscience\/wp-content\/uploads\/sites\/14\/2025\/05\/\u0648\u0635\u0641-\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c-\u0627\u0644\u0627\u0643\u0627\u062f\u064a\u0645\u064a-\u0648\u0627\u0644\u0645\u0642\u0631\u0631.pdf\">Click here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Academic program description 2023-2024\u00a0 \u00a0 Click here Academic program description 2024-2025\u00a0 \u00a0 Click here<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-40564","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/40564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/comments?post=40564"}],"version-history":[{"count":5,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/40564\/revisions"}],"predecessor-version":[{"id":42338,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/40564\/revisions\/42338"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/media?parent=40564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}