{"id":41981,"date":"2025-05-24T02:29:52","date_gmt":"2025-05-24T02:29:52","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/?page_id=41981"},"modified":"2025-05-24T02:37:15","modified_gmt":"2025-05-24T02:37:15","slug":"department-of-environmental-health-lectures-second-stage","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-health-lectures-second-stage\/","title":{"rendered":"Department of Environmental Health\\ Lectures\\ Second Stage"},"content":{"rendered":"<p><a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-health-lectures-second-stage-semester-1\/\">Semester 1<\/a><br \/>\n<a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-health-lectures-second-stage-semester-2\/\">Semester 2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Semester 1 Semester 2<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-41981","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/41981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/comments?post=41981"}],"version-history":[{"count":4,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/41981\/revisions"}],"predecessor-version":[{"id":41997,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/41981\/revisions\/41997"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/media?parent=41981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}