{"id":42038,"date":"2025-05-24T09:18:23","date_gmt":"2025-05-24T09:18:23","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/?page_id=42038"},"modified":"2025-05-24T09:18:23","modified_gmt":"2025-05-24T09:18:23","slug":"department-of-environmental-health-lectures-second-stage-semester-1-biostatistics-practical","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-health-lectures-second-stage-semester-1-biostatistics-practical\/","title":{"rendered":"Department of Environmental Health\\ Lectures\\ Second Stage\\ Semester 1\\ Biostatistics\\ Practical"},"content":{"rendered":"<p><a href=\"https:\/\/uomosul.edu.iq\/environmentalscience\/wp-content\/uploads\/sites\/14\/2024\/12\/%D8%A7%D8%AE%D8%B5%D8%A7%D8%A1-%D8%AD%D9%8A%D8%A7%D8%AA%D9%8A-.pdf\">\u00a0Life Statistics \/ practical\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Life Statistics \/ practical\u00a0<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42038","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/comments?post=42038"}],"version-history":[{"count":1,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42038\/revisions"}],"predecessor-version":[{"id":42040,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42038\/revisions\/42040"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/media?parent=42038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}