{"id":42169,"date":"2025-05-24T12:57:12","date_gmt":"2025-05-24T12:57:12","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/?page_id=42169"},"modified":"2025-05-26T10:40:36","modified_gmt":"2025-05-26T10:40:36","slug":"department-of-environmental-technology-lectures-stage-1-semester-one","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-technology-lectures-stage-1-semester-one\/","title":{"rendered":"Department of Environmental Science \\ Lectures \\ Stage 1\\ Semester One"},"content":{"rendered":"<p>Earth Science: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-science-lectures-stage-1-semester-one-earth-science\/\">Click here<\/a><\/p>\n<p>Organic Chemistry: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-science-lectures-stage-1-semester-one-organic-chemistry\/\">Click here<\/a><\/p>\n<p>Biology: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-science-lectures-stage-1-semester-one-biology\/\">Click here<\/a><\/p>\n<p>physics:\u00a0 <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-science-lectures-stage-1-semester-one-physics\/\">Click here<\/a><\/p>\n<p>Computer:\u00a0 \u00a0<a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-science-lectures-stage-1-semester-one-computer\/\">Click here<\/a><\/p>\n<p>English:\u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-science-lectures-stage-1-semester-one-english\/\">Click here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Earth Science: Click here Organic Chemistry: Click here Biology: Click here physics:\u00a0 Click here Computer:\u00a0 \u00a0Click here English:\u00a0 \u00a0 Click here<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42169","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/comments?post=42169"}],"version-history":[{"count":14,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42169\/revisions"}],"predecessor-version":[{"id":42664,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42169\/revisions\/42664"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/media?parent=42169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}