{"id":42483,"date":"2025-05-25T12:53:32","date_gmt":"2025-05-25T12:53:32","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/?page_id=42483"},"modified":"2025-05-25T13:04:34","modified_gmt":"2025-05-25T13:04:34","slug":"department-of-environmental-sciences-lectures-stage-4-semester-one","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one\/","title":{"rendered":"Department of Environmental Sciences \\ Lectures \\ Stage 4\\ Semester One"},"content":{"rendered":"<p>Atmospheric Chemistry: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one-atmospheric-chemistry\/\">Click here<\/a><\/p>\n<p>Health and Safety: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one-health-and-safety\/\">Click here<\/a><\/p>\n<p>Sustainable Development: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one-sustainable-development\/\">Click here<\/a><\/p>\n<p>Costs: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one-costs\/\">Click here<\/a><\/p>\n<p>Applications:<a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one-applications\/\"> Click here<\/a><\/p>\n<p>Rules and Regulations: <a href=\"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-sciences-lectures-stage-4-semester-one-rules-and-regulations\/\">Click here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atmospheric Chemistry: Click here Health and Safety: Click here Sustainable Development: Click here Costs: Click here Applications: Click here Rules and Regulations: Click here<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42483","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/comments?post=42483"}],"version-history":[{"count":4,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42483\/revisions"}],"predecessor-version":[{"id":42504,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42483\/revisions\/42504"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/media?parent=42483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}