{"id":42613,"date":"2025-05-25T22:11:29","date_gmt":"2025-05-25T22:11:29","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/?page_id=42613"},"modified":"2025-05-25T22:18:03","modified_gmt":"2025-05-25T22:18:03","slug":"department-of-environmental-health-course-descriptions-based-on-the-bologna-process-2023-2024-semester-two","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/department-of-environmental-health-course-descriptions-based-on-the-bologna-process-2023-2024-semester-two\/","title":{"rendered":"Department of Environmental Health\\ Course descriptions based on the Bologna Process 2023-2024\\ Semester Two"},"content":{"rendered":"<p>Course descriptions based on the Bologna Process 2023-2024\u00a0 \u00a0 <a href=\"https:\/\/uomosul.edu.iq\/environmentalscience\/wp-content\/uploads\/sites\/14\/2025\/05\/%D9%812.pdf\">click here<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Course descriptions based on the Bologna Process 2023-2024\u00a0 \u00a0 click here<\/p>\n","protected":false},"author":33,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-42613","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/comments?post=42613"}],"version-history":[{"count":3,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42613\/revisions"}],"predecessor-version":[{"id":42619,"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/pages\/42613\/revisions\/42619"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/environmentalscience\/wp-json\/wp\/v2\/media?parent=42613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}