{"id":37225,"date":"2025-05-12T09:00:52","date_gmt":"2025-05-12T09:00:52","guid":{"rendered":"https:\/\/uomosul.edu.iq\/en\/rights\/?page_id=37225"},"modified":"2025-05-13T08:01:08","modified_gmt":"2025-05-13T08:01:08","slug":"college-in-brief","status":"publish","type":"page","link":"https:\/\/uomosul.edu.iq\/en\/rights\/college-in-brief\/","title":{"rendered":"College in Brief"},"content":{"rendered":"<p><a href=\"https:\/\/uomosul.edu.iq\/en\/rights\/wp-content\/uploads\/sites\/20\/2023\/10\/College-of-Law-in-brief.pdf\">College of Law in brief<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>College of Law in brief<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-37225","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/pages\/37225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/comments?post=37225"}],"version-history":[{"count":4,"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/pages\/37225\/revisions"}],"predecessor-version":[{"id":38937,"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/pages\/37225\/revisions\/38937"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/en\/rights\/wp-json\/wp\/v2\/media?parent=37225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}