{"id":37403,"date":"2025-03-19T18:05:48","date_gmt":"2025-03-19T15:05:48","guid":{"rendered":"https:\/\/uomosul.edu.iq\/sport\/?p=37403"},"modified":"2025-10-07T14:07:24","modified_gmt":"2025-10-07T11:07:24","slug":"%d9%82%d8%b3%d9%85-%d8%a7%d9%84%d9%86%d8%b4%d8%a7%d8%b7%d8%a7%d8%aa-%d8%a7%d9%84%d8%b7%d9%84%d8%a7%d8%a8%d9%8a%d8%a9-%d9%8a%d9%82%d9%8a%d9%85-%d8%ad%d9%85%d9%84%d8%a9-%d8%aa%d8%b4%d8%ac%d9%8a%d8%b1","status":"publish","type":"post","link":"https:\/\/uomosul.edu.iq\/sport\/%d9%82%d8%b3%d9%85-%d8%a7%d9%84%d9%86%d8%b4%d8%a7%d8%b7%d8%a7%d8%aa-%d8%a7%d9%84%d8%b7%d9%84%d8%a7%d8%a8%d9%8a%d8%a9-%d9%8a%d9%82%d9%8a%d9%85-%d8%ad%d9%85%d9%84%d8%a9-%d8%aa%d8%b4%d8%ac%d9%8a%d8%b1\/","title":{"rendered":"\u0642\u0633\u0645 \u0627\u0644\u0646\u0634\u0627\u0637\u0627\u062a \u0627\u0644\u0637\u0644\u0627\u0628\u064a\u0629 \u064a\u0642\u064a\u0645 \u062d\u0645\u0644\u0629 \u062a\u0634\u062c\u064a\u0631&#8230;"},"content":{"rendered":"<p>\u0642\u0633\u0645 \u0627\u0644\u0646\u0634\u0627\u0637\u0627\u062a \u0627\u0644\u0637\u0644\u0627\u0628\u064a\u0629 \u064a\u0642\u064a\u0645 \u062d\u0645\u0644\u0629 \u062a\u0634\u062c\u064a\u0631&#8230;<img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-37404\" src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-300x200.jpg\" data-orig-src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-200x133.jpg 200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-300x200.jpg 300w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-400x267.jpg 400w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-600x400.jpg 600w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-768x512.jpg 768w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-800x533.jpg 800w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-1024x683.jpg 1024w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-1200x800.jpg 1200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491926108_1214810873764525_7922034289284754883_n-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-37405\" src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-300x200.jpg\" data-orig-src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-200x133.jpg 200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-300x200.jpg 300w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-400x267.jpg 400w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-600x400.jpg 600w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-768x512.jpg 768w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-800x533.jpg 800w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-1024x683.jpg 1024w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-1200x800.jpg 1200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491950573_1214811007097845_1831427577291671161_n-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-37406\" src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-300x200.jpg\" data-orig-src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-200x133.jpg 200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-300x200.jpg 300w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-400x267.jpg 400w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-600x400.jpg 600w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-768x512.jpg 768w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-800x533.jpg 800w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-1024x683.jpg 1024w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-1200x800.jpg 1200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491044562_1214810477097898_1727826968477378855_n-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-37407\" src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-300x200.jpg\" data-orig-src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-200x133.jpg 200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-300x200.jpg 300w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-400x267.jpg 400w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-600x400.jpg 600w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-768x512.jpg 768w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-800x533.jpg 800w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-1024x683.jpg 1024w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-1200x800.jpg 1200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491268219_1214810467097899_3868332629295241439_n-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-37408\" src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-300x200.jpg\" data-orig-src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-200x133.jpg 200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-300x200.jpg 300w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-400x267.jpg 400w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-600x400.jpg 600w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-768x512.jpg 768w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-800x533.jpg 800w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-1024x683.jpg 1024w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-1200x800.jpg 1200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491352110_1214808377098108_3430832226648428043_n-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"lazyload alignnone size-medium wp-image-37409\" src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491409550_1214808660431413_2406069628258561264_n-300x200.jpg\" data-orig-src=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491409550_1214808660431413_2406069628258561264_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491409550_1214808660431413_2406069628258561264_n-200x133.jpg 200w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491409550_1214808660431413_2406069628258561264_n-300x200.jpg 300w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491409550_1214808660431413_2406069628258561264_n-400x266.jpg 400w, https:\/\/uomosul.edu.iq\/sport\/wp-content\/uploads\/sites\/41\/2025\/05\/491409550_1214808660431413_2406069628258561264_n.jpg 593w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0642\u0633\u0645 \u0627\u0644\u0646\u0634\u0627\u0637\u0627\u062a \u0627\u0644\u0637\u0644\u0627\u0628\u064a\u0629 \u064a\u0642\u064a\u0645 \u062d\u0645\u0644\u0629 \u062a\u0634\u062c\u064a\u0631&#8230;<\/p>\n","protected":false},"author":43,"featured_media":37407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-37403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1"],"_links":{"self":[{"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/posts\/37403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/comments?post=37403"}],"version-history":[{"count":1,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/posts\/37403\/revisions"}],"predecessor-version":[{"id":37410,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/posts\/37403\/revisions\/37410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/media\/37407"}],"wp:attachment":[{"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/media?parent=37403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/categories?post=37403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uomosul.edu.iq\/sport\/wp-json\/wp\/v2\/tags?post=37403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}